{"id":7442,"date":"2025-12-01T11:37:38","date_gmt":"2025-12-01T11:37:38","guid":{"rendered":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg"},"modified":"2025-12-01T11:37:38","modified_gmt":"2025-12-01T11:37:38","slug":"_jam1821-2","status":"inherit","type":"attachment","link":"https:\/\/www.relationalontology.org\/en\/2025\/11\/10\/attualita-della-ricerca-dottorale-seminario-congiunto\/_jam1821-2\/","title":{"rendered":"_JAM1821"},"author":12,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":""},"class_list":["post-7442","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<h2 class=\"sub-title-primary\"><\/h2> <p class=\"attachment\"><a href='https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg 1280w, https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-768x512.jpeg 768w, https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-1080x720.jpeg 1080w, https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-610x407.jpeg 610w, https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-930x620.jpeg 930w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":853,"file":"2025\/11\/JAM1821.jpeg","filesize":224439,"sizes":{"medium_large":{"file":"JAM1821-768x512.jpeg","width":768,"height":512,"filesize":59641,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-768x512.jpeg"},"et-pb-post-main-image":{"file":"JAM1821-400x250.jpeg","width":400,"height":250,"filesize":20550,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-400x250.jpeg"},"et-pb-post-main-image-fullwidth":{"file":"JAM1821-1080x675.jpeg","width":1080,"height":675,"filesize":97460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-1080x675.jpeg"},"et-pb-portfolio-image":{"file":"JAM1821-400x284.jpeg","width":400,"height":284,"filesize":21668,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-400x284.jpeg"},"et-pb-portfolio-module-image":{"file":"JAM1821-510x382.jpeg","width":510,"height":382,"filesize":32189,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-510x382.jpeg"},"et-pb-portfolio-image-single":{"file":"JAM1821-1080x720.jpeg","width":1080,"height":720,"filesize":101560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-1080x720.jpeg"},"et-pb-gallery-module-image-portrait":{"file":"JAM1821-400x516.jpeg","width":400,"height":516,"filesize":25278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-400x516.jpeg"},"bloom_image":{"file":"JAM1821-610x407.jpeg","width":610,"height":407,"filesize":41717,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-610x407.jpeg"},"neve-blog":{"file":"JAM1821-930x620.jpeg","width":930,"height":620,"filesize":80933,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821-930x620.jpeg"},"full":{"file":"JAM1821.jpeg","width":1280,"height":853,"mime_type":"image\/jpeg","source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":7404,"source_url":"https:\/\/www.relationalontology.org\/wp-content\/uploads\/2025\/11\/JAM1821.jpeg","_links":{"self":[{"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/media\/7442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/comments?post=7442"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7404,"href":"https:\/\/www.relationalontology.org\/en\/wp-json\/wp\/v2\/posts\/7404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}